{"id":10000861,"date":"2026-07-09T10:01:57","date_gmt":"2026-07-09T13:01:57","guid":{"rendered":"https:\/\/experienceparkland.com\/?post_type=tribe_events&#038;p=18685"},"modified":"2026-07-13T11:05:14","modified_gmt":"2026-07-13T14:05:14","slug":"bbq-tour","status":"publish","type":"tribe_events","link":"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/","title":{"rendered":"Weekly BBQ &amp; Tours"},"content":{"rendered":"<p>Enjoy complimentary BBQs every Wednesday this summer!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Enjoy complimentary BBQs every Wednesday this summer!<\/p>\n","protected":false},"author":141,"featured_media":18699,"template":"","meta":{"_acf_changed":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[69],"class_list":["post-10000861","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tribe_events_cat-community","cat_community","tribe-recurring-event","tribe-recurring-event-parent"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weekly BBQ &amp; Tours - Parkland Retirement Living<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weekly BBQ &amp; Tours - Parkland Retirement Living\" \/>\n<meta property=\"og:description\" content=\"Enjoy complimentary BBQs every Wednesday this summer!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/\" \/>\n<meta property=\"og:site_name\" content=\"Parkland Retirement Living\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-13T14:05:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/experienceparkland.com\/wp-content\/uploads\/2026\/07\/Weekly_BBQTours_Hero-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"680\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/event\\\/bbq-tour\\\/2027-02-17\\\/\",\"url\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/event\\\/bbq-tour\\\/2027-02-17\\\/\",\"name\":\"Weekly BBQ &amp; Tours - Parkland Retirement Living\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/event\\\/bbq-tour\\\/2027-02-17\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/event\\\/bbq-tour\\\/2027-02-17\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/experienceparkland.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Weekly_BBQTours_Hero-1.jpg\",\"datePublished\":\"2026-07-09T13:01:57+00:00\",\"dateModified\":\"2026-07-13T14:05:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/event\\\/bbq-tour\\\/2027-02-17\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/experienceparkland.com\\\/en\\\/event\\\/bbq-tour\\\/2027-02-17\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/event\\\/bbq-tour\\\/2027-02-17\\\/#primaryimage\",\"url\":\"https:\\\/\\\/experienceparkland.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Weekly_BBQTours_Hero-1.jpg\",\"contentUrl\":\"https:\\\/\\\/experienceparkland.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/Weekly_BBQTours_Hero-1.jpg\",\"width\":2560,\"height\":680},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/event\\\/bbq-tour\\\/2027-02-17\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Events\",\"item\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weekly BBQ &amp; Tours\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/\",\"name\":\"Parkland Retirement Living\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/experienceparkland.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weekly BBQ &amp; Tours - Parkland Retirement Living","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/","og_locale":"en_US","og_type":"article","og_title":"Weekly BBQ &amp; Tours - Parkland Retirement Living","og_description":"Enjoy complimentary BBQs every Wednesday this summer!","og_url":"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/","og_site_name":"Parkland Retirement Living","article_modified_time":"2026-07-13T14:05:14+00:00","og_image":[{"width":2560,"height":680,"url":"https:\/\/experienceparkland.com\/wp-content\/uploads\/2026\/07\/Weekly_BBQTours_Hero-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/","url":"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/","name":"Weekly BBQ &amp; Tours - Parkland Retirement Living","isPartOf":{"@id":"https:\/\/experienceparkland.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/#primaryimage"},"image":{"@id":"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/#primaryimage"},"thumbnailUrl":"https:\/\/experienceparkland.com\/wp-content\/uploads\/2026\/07\/Weekly_BBQTours_Hero-1.jpg","datePublished":"2026-07-09T13:01:57+00:00","dateModified":"2026-07-13T14:05:14+00:00","breadcrumb":{"@id":"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/#primaryimage","url":"https:\/\/experienceparkland.com\/wp-content\/uploads\/2026\/07\/Weekly_BBQTours_Hero-1.jpg","contentUrl":"https:\/\/experienceparkland.com\/wp-content\/uploads\/2026\/07\/Weekly_BBQTours_Hero-1.jpg","width":2560,"height":680},{"@type":"BreadcrumbList","@id":"https:\/\/experienceparkland.com\/en\/event\/bbq-tour\/2027-02-17\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/experienceparkland.com\/en\/"},{"@type":"ListItem","position":2,"name":"Events","item":"https:\/\/experienceparkland.com\/en\/events\/"},{"@type":"ListItem","position":3,"name":"Weekly BBQ &amp; Tours"}]},{"@type":"WebSite","@id":"https:\/\/experienceparkland.com\/en\/#website","url":"https:\/\/experienceparkland.com\/en\/","name":"Parkland Retirement Living","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/experienceparkland.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/experienceparkland.com\/en\/wp-json\/wp\/v2\/tribe_events\/10000861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/experienceparkland.com\/en\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/experienceparkland.com\/en\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/experienceparkland.com\/en\/wp-json\/wp\/v2\/users\/141"}],"version-history":[{"count":0,"href":"https:\/\/experienceparkland.com\/en\/wp-json\/wp\/v2\/tribe_events\/10000861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/experienceparkland.com\/en\/wp-json\/wp\/v2\/media\/18699"}],"wp:attachment":[{"href":"https:\/\/experienceparkland.com\/en\/wp-json\/wp\/v2\/media?parent=10000861"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/experienceparkland.com\/en\/wp-json\/wp\/v2\/tags?post=10000861"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/experienceparkland.com\/en\/wp-json\/wp\/v2\/tribe_events_cat?post=10000861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}